{"id":20102,"date":"2024-09-27T09:38:36","date_gmt":"2024-09-27T13:38:36","guid":{"rendered":"https:\/\/asgrq.ca\/?page_id=20102"},"modified":"2025-09-29T17:55:25","modified_gmt":"2025-09-29T21:55:25","slug":"terre-la-durantaye","status":"publish","type":"page","link":"https:\/\/asgrq.ca\/en\/accueil\/terre-la-durantaye\/","title":{"rendered":"Terre La Durantaye"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"20102\" class=\"elementor elementor-20102\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce3852e e-flex e-con-boxed e-con e-parent\" data-id=\"ce3852e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1410b8c elementor-widget elementor-widget-heading\" data-id=\"1410b8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">R\u00e9servation d\u2019une terre agricole pour la chasse \u00e0 la sauvagine au b\u00e9n\u00e9fice des membres de l\u2019ASRGQ<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e01143 elementor-widget elementor-widget-text-editor\" data-id=\"1e01143\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le Conseil d\u2019administration de l\u2019ASGRQ est heureux de vous informer qu\u2019un partenariat a \u00e9t\u00e9 \u00e9tabli avec le propri\u00e9taire d\u2019une terre agricole situ\u00e9e \u00e0 proximit\u00e9 du refuge d\u2019oiseaux migrateurs Saint-Vallier, secteur fr\u00e9quent\u00e9 par plusieurs esp\u00e8ces de sauvagine en p\u00e9riode migratoire.<\/p><p>En vertu de ce partenariat, ladite terre agricole est r\u00e9serv\u00e9e par l\u2019ASGRQ afin de permettre \u00e0 nos membres d\u2019y pratiquer la chasse \u00e0 la sauvagine \u00e0 raison de 4 jours semaine, soit deux jours sur semaine ainsi que les samedis, et les dimanches. \u00a0Les frais sont de 140$ par journ\u00e9e de chasse et ce pour un maximum de 5 chasseurs, lesquels doivent tous \u00eatre membres en r\u00e8gle de l\u2019ASGRQ. La totalit\u00e9 des sommes recueillies sera ult\u00e9rieurement remise au propri\u00e9taire de ladite terre.<\/p><p>Afin de bien coordonner le processus de r\u00e9servation des dates de chasse, consultez le calendrier pour la saison de chasse de l&rsquo;automne 2025 ainsi que les r\u00e8glements applicables ci-dessous. Les r\u00e9servations seront ouvertes \u00e0 partir de septembre 2025 pour tous les membres en r\u00e8gle de l&rsquo;ASGRQ. Aucun remboursement de frais ne sera effectu\u00e9 par l\u2019ASGRQ. Les participants doivent apporter leurs \u00e9quipements, tel que caches, appelants, appeaux, etc.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-78e241a e-con-full e-flex e-con e-parent\" data-id=\"78e241a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0e38a4d e-con-full e-flex e-con e-child\" data-id=\"0e38a4d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c5c427 elementor-widget elementor-widget-heading\" data-id=\"2c5c427\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Modalit\u00e9s de r\u00e9servation<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a40399 elementor-widget elementor-widget-text-editor\" data-id=\"8a40399\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les r\u00e9servations et le paiement se font par courriel \u00e0 info@asgrq.ca, selon la r\u00e8gle du premier arriv\u00e9 premier servi (date et heure du courriel faisant foi). Les r\u00e9servations non conformes ou incompl\u00e8tes seront rejet\u00e9es.<\/p><p>\u00c9tape 1 &#8211; Consulter le calendrier des jours de chasse disponibles.<\/p><p>\u00c9tape 2 &#8211; S\u00e9lectionner une date disponible.<\/p><p>\u00c9tape 3 &#8211; Remplir le formulaire disponible sur cette page (incluant tous les renseignements n\u00e9cessaires demand\u00e9s).<\/p><p>\u00c9tape 4 &#8211; Proc\u00e9der au paiement de 140 $ via Interac \u00e0:<\/p><ul><li><a href=\"mailto:info@asgrq.ca\">info@asgrq.ca<\/a><\/li><\/ul><p>La r\u00e9servation sera effective une fois le paiement ex\u00e9cut\u00e9.<\/p><p>\u00c9tape 5 &#8211; Une confirmation de r\u00e9servation sera envoy\u00e9e par courriel au requ\u00e9rant.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57e480a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"57e480a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/asgrq.ca\/wp-content\/uploads\/2024\/10\/REGLEMENTS-VISANT-LA-CHASSE-SUR-LA-TERRE-RESERVEE-PAR-L.pdf\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">R\u00c8GLEMENTS VISANT LA CHASSE SUR LA TERRE R\u00c9SERV\u00c9E PAR L\u2019ASGRQ<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59a78b0 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"59a78b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/asgrq.ca\/wp-content\/uploads\/2025\/09\/ITINERAIRE-POUR-ACCEDER-A-LA-TERRE2.pdf\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Itin\u00e9raire pour acc\u00e9der \u00e0 la terre<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8611d5 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"f8611d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/maps.app.goo.gl\/eZy5St2EK85Z7QgG8\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Liens  vers google Maps<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a27213a e-con-full e-flex e-con e-child\" data-id=\"a27213a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-033ac4e elementor-widget elementor-widget-shortcode\" data-id=\"033ac4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"> <div id=\"form_id1646705104369\" class=\"wpbc_container wpbc_form wpbc_container_booking_form\" ><form id=\"booking_form1\" class=\"booking_form vertical\" method=\"post\" action=\"\" data-trp-original-action=\"\"><div id=\"ajax_respond_insert1\" class=\"ajax_respond_insert\" style=\"display:none;\"><\/div><a name=\"bklnk1\" id=\"bklnk1\"><\/a><div id=\"booking_form_div1\" class=\"booking_form_div\"><style type=\"text\/css\">.wpbc_container_booking_form .block_hints, .wpbc_booking_form_simple.wpbc_form_center .wpbc__form__div .wpbc__row.wpbc_r_calendar, .wpbc_booking_form_simple .wpbc__form__div .wpbc__row:not(.wpbc_r_calendar){max-width:440px;} <\/style>\n<div class=\"wpbc_booking_form_simple\">\n<div class=\"wpbc__row\">\n  <div class=\"wpbc__field\">\n    <div class=\"wpbc_calendar_wraper wpbc_change_over_triangle wpbc_calendar_skin_legacy\"><div class=\"wpbc_cal_container bk_calendar_frame wpbc_no_custom_width  months_num_in_row_ cal_month_num_1\" style=\"\"><div id=\"calendar_booking1\"  class=\"wpbc_calendar_id_1\" >\t<div class=\"calendar_loader_frame calendar_loader_frame1\"\r\n\t\tdata-wpbc-rid=\"1\"\r\n\t\tdata-wpbc-grace=\"8000\"\r\n\t\tstyle=\"--wpbc-loader-cols: 1;\"\r\n\t>\r\n\t\t<div class=\"calendar_loader_text\">Loading...<\/div>\r\n\t\t<div class=\"calendar_loader_frame__progress_line_container\">\r\n\t\t\t<div class=\"calendar_loader_frame__progress_line\"><\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t<\/div><\/div><div style=\"font-size:7px;text-align:left;margin:0 0 10px;text-shadow: none;\">Powered by <a href=\"https:\/\/wpbookingcalendar.com\" style=\"font-size:7px;\" target=\"_blank\" title=\"Booking Calendar plugin for WordPress\">Booking Calendar<\/a><\/div><textarea id=\"date_booking1\" name=\"date_booking1\" autocomplete=\"off\" style=\"display:none;\"><\/textarea><div class=\"block_hints datepick\"><div class=\"wpdev_hint_with_text\"><div class=\"\"><div class=\"datepick-inline wpbc_calendar_legend_table_width_height\"><table class=\"datepick wpbc_calendar\" style=\"\"><tbody><tr><td class=\"datepick-days-cell date_available wpbc_calendar_legend_day_cell_height\"><div class=\"wpbc-cell-box\">\t<div class=\"date-cell-content\">\t\t<div class=\"date-content-top\"><\/div>\t\t<a>15<\/a>\t\t<div class=\"date-content-bottom\"><\/div>\t<\/div><\/div><\/td><\/tr><\/tbody><\/table><\/div><\/div><div class=\"block_text\">- <\/div><div class=\"block_text\">Disponible<\/div><\/div><div class=\"wpdev_hint_with_text\"><div class=\"\"><div class=\"datepick-inline wpbc_calendar_legend_table_width_height\"><table class=\"datepick wpbc_calendar\" style=\"\"><tbody><tr><td class=\"datepick-days-cell datepick-unselectable date_user_unavailable full_day_booking date_approved wpbc_calendar_legend_day_cell_height\"><div class=\"wpbc-cell-box\">\t<div class=\"date-cell-content\">\t\t<div class=\"date-content-top\"><\/div>\t\t<span>15<\/span>\t\t<div class=\"date-content-bottom\"><\/div>\t<\/div><\/div><\/td><\/tr><\/tbody><\/table><\/div><\/div><div class=\"block_text\">- <\/div><div class=\"block_text\">R\u00e9serv\u00e9<\/div><\/div><div class=\"wpdev_hint_with_text\"><div class=\"\"><div class=\"datepick-inline wpbc_calendar_legend_table_width_height\"><table class=\"datepick wpbc_calendar\" style=\"\"><tbody><tr><td class=\"datepick-days-cell datepick-unselectable date_user_unavailable full_day_booking date2approve wpbc_calendar_legend_day_cell_height\"><div class=\"wpbc-cell-box\">\t<div class=\"date-cell-content\">\t\t<div class=\"date-content-top\"><\/div>\t\t<span>15<\/span>\t\t<div class=\"date-content-bottom\"><\/div>\t<\/div><\/div><\/td><\/tr><\/tbody><\/table><\/div><\/div><div class=\"block_text\">- <\/div><div class=\"block_text\">En attente d&#039;approbation<\/div><\/div><\/div><\/div>\n  <\/div>\n  <div class=\"wpbc__field\">\n<div class=\"wpbc__form__div\">\n\t\t\t<div class=\"wpbc__row\">\n\t\t\t\t<div class=\"wpbc_r_name wpbc__field\"> <label>Pr\u00e9nom*<\/label><br><span class=\"wpbc_wrap_text wpdev-form-control-wrap name1\"><input type=\"text\" name=\"name1\" value=\"\" autocomplete=\"name\" class=\"wpdev-validates-as-required\" size=\"40\" \/><\/span> <\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wpbc__row\">\n\t\t\t\t<div class=\"wpbc_r_secondname wpbc__field\"> <label>Nom*<\/label><br><span class=\"wpbc_wrap_text wpdev-form-control-wrap secondname1\"><input type=\"text\" name=\"secondname1\" value=\"\" autocomplete=\"secondname\" class=\"wpdev-validates-as-required\" size=\"40\" \/><\/span> <\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wpbc__row\">\n\t\t\t\t<div class=\"wpbc_r_email wpbc__field\"> <label>Courriel*<\/label><br><span class=\"wpbc_wrap_text wpdev-form-control-wrap email1\"><input type=\"email\" name=\"email1\" value=\"\" autocomplete=\"email\" class=\"wpdev-validates-as-email wpdev-validates-as-required\" size=\"40\" \/><\/span> <\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wpbc__row\">\n\t\t\t\t<div class=\"wpbc_r_phone wpbc__field\"> <label>T\u00e9l\u00e9phone<\/label><br><span class=\"wpbc_wrap_text wpdev-form-control-wrap phone1\"><input type=\"text\" name=\"phone1\" value=\"\" autocomplete=\"phone\" size=\"40\" \/><\/span> <\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wpbc__row\">\n\t\t\t\t<div class=\"wpbc_r_visitors wpbc__field\"> <label>Nombre de chasseurs*<\/label><br><span class=\"wpbc_wrap_select wpdev-form-control-wrap visitors1\"><select onchange=\"javascript:if(typeof( wpbc_show_cost_hints_after_few_seconds )=='function'){wpbc_show_cost_hints_after_few_seconds(1);}\" name=\"visitors1\" autocomplete=\"visitors\" class=\"wpdev-validates-as-required\"><option value=\"1\">1<\/option><option value=\"2\">2<\/option><option value=\"3\">3<\/option><option value=\"4\">4<\/option><option value=\"5\">5<\/option><\/select><\/span> <\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wpbc__row\">\n\t\t\t\t<div class=\"wpbc_r_details wpbc__field\"> <label>Nom des chasseurs<\/label><br><span class=\"wpbc_wrap_textarea wpdev-form-control-wrap details1\"><textarea name=\"details1\" autocomplete=\"details\"><\/textarea><\/span> <\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wpbc__row\">\n\t\t\t\t<div class=\"wpbc_r_submit wpbc__field\"><input type=\"button\" value=\"Envoyer\" class=\"wpbc_button_light  btn btn\" onclick=\"wpbc_booking_form_submit(this.form,1, 'en_CA');\" \/> <\/div>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><input id=\"bk_type1\" name=\"bk_type1\" class=\"\" type=\"hidden\" value=\"1\" \/><\/div><div id=\"submiting1\"><\/div><div class=\"form_bk_messages\" id=\"form_bk_messages1\" ><\/div><input type=\"hidden\" id=\"wpbc_nonceCALCULATE_THE_COST1\" name=\"wpbc_nonceCALCULATE_THE_COST1\" value=\"7a57f04b71\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/en\/wp-json\/wp\/v2\/pages\/20102\" \/><input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form><\/div><div id=\"booking_form_garbage1\" class=\"booking_form_garbage\"><\/div> <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>R\u00e9servation d\u2019une terre agricole pour la chasse \u00e0 la sauvagine au b\u00e9n\u00e9fice des membres de l\u2019ASRGQ Le Conseil d\u2019administration de l\u2019ASGRQ est heureux de vous informer qu\u2019un partenariat a \u00e9t\u00e9 \u00e9tabli avec le propri\u00e9taire d\u2019une terre agricole situ\u00e9e \u00e0 proximit\u00e9 du refuge d\u2019oiseaux migrateurs Saint-Vallier, secteur fr\u00e9quent\u00e9 par plusieurs esp\u00e8ces de sauvagine en p\u00e9riode migratoire. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":583,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"pmpro_default_level":"","inline_featured_image":false,"footnotes":""},"class_list":["post-20102","page","type-page","status-publish","hentry","pmpro-has-access"],"_links":{"self":[{"href":"https:\/\/asgrq.ca\/en\/wp-json\/wp\/v2\/pages\/20102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asgrq.ca\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/asgrq.ca\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/asgrq.ca\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/asgrq.ca\/en\/wp-json\/wp\/v2\/comments?post=20102"}],"version-history":[{"count":85,"href":"https:\/\/asgrq.ca\/en\/wp-json\/wp\/v2\/pages\/20102\/revisions"}],"predecessor-version":[{"id":20816,"href":"https:\/\/asgrq.ca\/en\/wp-json\/wp\/v2\/pages\/20102\/revisions\/20816"}],"up":[{"embeddable":true,"href":"https:\/\/asgrq.ca\/en\/wp-json\/wp\/v2\/pages\/583"}],"wp:attachment":[{"href":"https:\/\/asgrq.ca\/en\/wp-json\/wp\/v2\/media?parent=20102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}